{"id":2665,"date":"2017-12-26T12:00:00","date_gmt":"2017-12-26T14:00:00","guid":{"rendered":"https:\/\/medriocheckup-com-br.umbler.net\/2017\/12\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/"},"modified":"2017-12-26T12:00:00","modified_gmt":"2017-12-26T14:00:00","slug":"coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc","status":"publish","type":"post","link":"https:\/\/spcheckup.com.br\/fr\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/","title":{"rendered":"Coluna Ancelmo Gois &#8211; O Globo &#8211; Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC"},"content":{"rendered":"<p><img decoding=\"async\" width=\"1100\" height=\"506\" src=\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\" data-orig-src=\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\" class=\"lazyload attachment-full size-full\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271100%27%20height%3D%27506%27%20viewBox%3D%270%200%201100%20506%27%3E%3Crect%20width%3D%271100%27%20height%3D%27506%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png 1100w, https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612-300x138.png 300w, https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612-768x353.png 768w, https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612-1024x471.png 1024w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1,94],"tags":[],"class_list":["post-2665","post","type-post","status-publish","format-image","hentry","category-nao-categorizado","category-o-globo","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/\" \/>\n<meta property=\"og:site_name\" content=\"SP Check-up\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-26T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medriocheck-up.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/\",\"url\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/\",\"name\":\"Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up\",\"isPartOf\":{\"@id\":\"https:\/\/spcheckup.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\",\"datePublished\":\"2017-12-26T14:00:00+00:00\",\"dateModified\":\"2017-12-26T14:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/spcheckup.com.br\/#\/schema\/person\/c1c7cd39c2a7a49f64a81e13d98ed4a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage\",\"url\":\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\",\"contentUrl\":\"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/spcheckup.com.br\/maintenance-page\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coluna Ancelmo Gois &#8211; O Globo &#8211; Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/spcheckup.com.br\/#website\",\"url\":\"https:\/\/spcheckup.com.br\/\",\"name\":\"SP Check-UP\",\"description\":\"O seu check-up m\u00e9dico. L\u00edder brasileira e especializada em medicina preventiva desde 1990, a Med-Rio Check-up j\u00e1 realizou mais de 160.000 check-ups m\u00e9dicos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/spcheckup.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/spcheckup.com.br\/#\/schema\/person\/c1c7cd39c2a7a49f64a81e13d98ed4a2\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/spcheckup.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a1dfa5dc0ca196b1f09f02810a32a35e322f1dbea273ead381955a9b8372db81?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a1dfa5dc0ca196b1f09f02810a32a35e322f1dbea273ead381955a9b8372db81?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/spcheckup.com.br\/fr\/author\/agenciab5\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up","og_url":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/","og_site_name":"SP Check-up","article_published_time":"2017-12-26T14:00:00+00:00","og_image":[{"url":"https:\/\/medriocheck-up.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/","url":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/","name":"Coluna Ancelmo Gois - O Globo - Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC - SP Check-up","isPartOf":{"@id":"https:\/\/spcheckup.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage"},"image":{"@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage"},"thumbnailUrl":"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png","datePublished":"2017-12-26T14:00:00+00:00","dateModified":"2017-12-26T14:00:00+00:00","author":{"@id":"https:\/\/spcheckup.com.br\/#\/schema\/person\/c1c7cd39c2a7a49f64a81e13d98ed4a2"},"breadcrumb":{"@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#primaryimage","url":"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png","contentUrl":"https:\/\/spcheckup.com.br\/wp-content\/uploads\/2018\/07\/med-rio-ancelmo-goes-2612.png"},{"@type":"BreadcrumbList","@id":"https:\/\/medriocheck-up.com.br\/coluna-ancelmo-gois-o-globo-diretor-da-med-rio-sera-um-dos-instrutores-do-curso-medicina-preventiva-aplicada-ao-estilo-de-vida-da-puc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/spcheckup.com.br\/maintenance-page\/"},{"@type":"ListItem","position":2,"name":"Coluna Ancelmo Gois &#8211; O Globo &#8211; Diretor da Med-Rio ser\u00e1 um dos instrutores do curso \u201cMedicina Preventiva aplicada ao estilo de vida\u201d, da PUC"}]},{"@type":"WebSite","@id":"https:\/\/spcheckup.com.br\/#website","url":"https:\/\/spcheckup.com.br\/","name":"SP Check-UP","description":"O seu check-up m\u00e9dico. L\u00edder brasileira e especializada em medicina preventiva desde 1990, a Med-Rio Check-up j\u00e1 realizou mais de 160.000 check-ups m\u00e9dicos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spcheckup.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/spcheckup.com.br\/#\/schema\/person\/c1c7cd39c2a7a49f64a81e13d98ed4a2","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spcheckup.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a1dfa5dc0ca196b1f09f02810a32a35e322f1dbea273ead381955a9b8372db81?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1dfa5dc0ca196b1f09f02810a32a35e322f1dbea273ead381955a9b8372db81?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/spcheckup.com.br\/fr\/author\/agenciab5\/"}]}},"_links":{"self":[{"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/posts\/2665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/comments?post=2665"}],"version-history":[{"count":0,"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/posts\/2665\/revisions"}],"wp:attachment":[{"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/media?parent=2665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/categories?post=2665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spcheckup.com.br\/fr\/wp-json\/wp\/v2\/tags?post=2665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}